{"id":214,"date":"2023-01-18T16:53:35","date_gmt":"2023-01-18T15:53:35","guid":{"rendered":"http:\/\/eudinecotte.com\/?page_id=214"},"modified":"2023-08-18T17:35:47","modified_gmt":"2023-08-18T15:35:47","slug":"a-mon-propos","status":"publish","type":"page","link":"https:\/\/www.eudinecotte.com\/index.php\/a-mon-propos\/","title":{"rendered":"Qui suis-je ?"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"214\" class=\"elementor elementor-214\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-45a1290 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"45a1290\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-da86f69\" data-id=\"da86f69\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ae1ee74 elementor-hidden-desktop elementor-widget elementor-widget-spacer\" data-id=\"ae1ee74\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-02f08eb elementor-widget elementor-widget-text-editor\" data-id=\"02f08eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1 style=\"text-align: left;\">Respect, \u00e9coute, soutien<\/h1>\n<div><\/div>\n<p style=\"text-align: justify;\">Durant mes ann\u00e9es d&rsquo;\u00e9tudes, j&rsquo;ai effectu\u00e9 plusieurs stages au sein d&rsquo;un r\u00e9giment militaire. Malgr\u00e9, les nombreuses difficult\u00e9s et contraintes que les militaires vivent au quotidien. Sur un plan plus personnel, le milieu militaire m&rsquo;a fait d\u00e9couvrir de nombreuses valeurs essentielles \u00e0 l&rsquo;Institution.<\/p>\n<p style=\"text-align: justify;\">Le <b>respect<\/b> de l&rsquo;autre, la <b>responsabilit\u00e9<\/b> <b>professionnelle<\/b>, l&rsquo;<b>engagement<\/b> et le <b>soutien <\/b>qu&rsquo;ils peuvent avoir les uns envers les autres sont des valeurs primordiales dans lesquelles je m&rsquo;engage \u00e0 vous accompagner dans votre d\u00e9marche r\u00e9flexive tout en \u00e9tant la plus <b>bienveillante<\/b> possible.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-091c2af\" data-id=\"091c2af\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f95c5dd elementor-widget elementor-widget-image\" data-id=\"f95c5dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.eudinecotte.com\/wp-content\/uploads\/2023\/04\/pexels-art-guzman-8079176-1-1024x683.jpg\" class=\"attachment-large size-large wp-image-1712\" alt=\"\" srcset=\"https:\/\/www.eudinecotte.com\/wp-content\/uploads\/2023\/04\/pexels-art-guzman-8079176-1-1024x683.jpg 1024w, https:\/\/www.eudinecotte.com\/wp-content\/uploads\/2023\/04\/pexels-art-guzman-8079176-1-300x200.jpg 300w, https:\/\/www.eudinecotte.com\/wp-content\/uploads\/2023\/04\/pexels-art-guzman-8079176-1-768x512.jpg 768w, https:\/\/www.eudinecotte.com\/wp-content\/uploads\/2023\/04\/pexels-art-guzman-8079176-1-1536x1024.jpg 1536w, https:\/\/www.eudinecotte.com\/wp-content\/uploads\/2023\/04\/pexels-art-guzman-8079176-1-2048x1365.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">La coop\u00e9ration<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b0749bc elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"b0749bc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d53a4d0\" data-id=\"d53a4d0\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9c04037 elementor-widget elementor-widget-image\" data-id=\"9c04037\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.eudinecotte.com\/wp-content\/uploads\/2023\/08\/pexels-bianca-1722050-scaled-1-1024x683.jpg\" class=\"attachment-large size-large wp-image-2263\" alt=\"\" srcset=\"https:\/\/www.eudinecotte.com\/wp-content\/uploads\/2023\/08\/pexels-bianca-1722050-scaled-1-1024x683.jpg 1024w, https:\/\/www.eudinecotte.com\/wp-content\/uploads\/2023\/08\/pexels-bianca-1722050-scaled-1-300x200.jpg 300w, https:\/\/www.eudinecotte.com\/wp-content\/uploads\/2023\/08\/pexels-bianca-1722050-scaled-1-768x512.jpg 768w, https:\/\/www.eudinecotte.com\/wp-content\/uploads\/2023\/08\/pexels-bianca-1722050-scaled-1-1536x1024.jpg 1536w, https:\/\/www.eudinecotte.com\/wp-content\/uploads\/2023\/08\/pexels-bianca-1722050-scaled-1-2048x1366.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Le syst\u00e8me<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b1fd2a7\" data-id=\"b1fd2a7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c31667f elementor-widget elementor-widget-text-editor\" data-id=\"c31667f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1 contenteditable=\"false\" data-elementor-setting-key=\"title\" data-pen-placeholder=\"\u00c9crivez ici...\"><\/h1>\n<h1 contenteditable=\"true\" data-elementor-setting-key=\"title\" data-pen-placeholder=\"\u00c9crivez ici...\">L&rsquo;individu dans un tout<\/h1>\n<div><\/div>\n<p style=\"text-align: justify;\">Selon moi, les connaissances du psychologue ne doivent pas se r\u00e9sumer uniquement \u00e0 la psychopathologie et aux concepts th\u00e9oriques. Bien qu&rsquo;il soit n\u00e9cessaire d&rsquo;avoir un minimum de connaissances th\u00e9oriques dans la pratique et continuer \u00e0 se former tout au long de ce m\u00e9tier. Il me para\u00eet primordial de porter une attention particuli\u00e8re aux divers domaines qui viennent impacter le bien-\u00eatre et la sant\u00e9 psychique.<\/p>\n<p style=\"text-align: justify;\"><b>Dans les suivis que je r\u00e9alise, j&rsquo;essaie de porter mon regard sur le syst\u00e8me global dans lequel le sujet se trouve, afin d&rsquo;avoir une meilleure vue d&rsquo;ensemble des difficult\u00e9s que le patient traverse et ce qu&rsquo;il soit sportif ou non.\u00a0<\/b><\/p>\n<p style=\"text-align: left;\"><b>\u00a0<\/b><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2ae115a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2ae115a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-01eae67\" data-id=\"01eae67\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b3a6594 elementor-widget elementor-widget-spacer\" data-id=\"b3a6594\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a673034 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a673034\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3c9de73\" data-id=\"3c9de73\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6843b1e elementor-widget elementor-widget-heading\" data-id=\"6843b1e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Dipl\u00f4mes et formations<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-87ae47a e-transform elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"87ae47a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_translateX_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b63c5e2 e-transform e-transform elementor-widget elementor-widget-text-editor\" data-id=\"b63c5e2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_translateY_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_skewX_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_skewX_effect_tablet&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_skewX_effect_mobile&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_skewY_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_skewY_effect_tablet&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_skewY_effect_mobile&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><b style=\"font-style: inherit;\">2022 &#8211; IFPEC<br \/><\/b><b style=\"font-style: inherit;\">EFT (Emotional Freedom Technique)<\/b><\/p><p style=\"text-align: center;\"><b>2021 &#8211;\u00a0<\/b><b>FormaPro Sophro<\/b><br \/>Sophro-p\u00e9dagie sportive<\/p><p style=\"text-align: center;\"><b>2021 &#8211;\u00a0<\/b><b>Institut Catholique de Toulouse<br \/><\/b>Master : Psychologie Clinique, Psychopathologie et Psychologie de la Sant\u00e9.<br \/><i>Parcours : Accompagnements des personnes en situation de d\u00e9pendance.<\/i><i>\u00a0<\/i><i>Sp\u00e9cialit\u00e9 : Handicap m\u00e9dico-psychologique.<\/i><\/p><p style=\"text-align: center;\"><b>2019 &#8211;\u00a0Institut Catholique de Toulouse<\/b><br \/>Licence Psychologie<br \/><i>Sp\u00e9cialisation :\u00a0<\/i><i>M\u00e9tiers des relations humaines et management.<br \/>(Analyse des risques psycho-sociaux. Pr\u00e9vention et bien-\u00eatre au travail.)<\/i><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a67ec1d\" data-id=\"a67ec1d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5bf7809 elementor-widget elementor-widget-heading\" data-id=\"5bf7809\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Exp\u00e9riences professionnelles<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5666df5 e-transform elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"5666df5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_translateX_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f0e78b3 e-transform e-transform elementor-widget elementor-widget-text-editor\" data-id=\"f0e78b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_translateY_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_skewX_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_skewX_effect_tablet&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_skewX_effect_mobile&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_skewY_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_skewY_effect_tablet&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_skewY_effect_mobile&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><span style=\"font-style: inherit;\"><b>Psychologue b\u00e9n\u00e9vole &#8211; Association \u00c9tincelle Occitanie &#8211; Toulouse<\/b><\/span><\/p>\n<p style=\"text-align: center;\"><b>Psychologue stagiaire Hospitalisation \u00c0 Domicile B\u00e9arn et Soule &#8211; Oloron-Sainte-Marie<\/b><br>2021<\/p>\n<p style=\"text-align: center;\"><b>Psychologue stagiaire MAS du Domaine des Roses &#8211; Rontignon<\/b><br>2021<\/p>\n<p style=\"text-align: center;\"><b>Psychologue stagiaire Conscience &amp; Orientation &#8211; Toulouse<\/b><br>2019<\/p>\n<p style=\"text-align: center;\"><b>Stagiaire Arm\u00e9e de Terre &#8211; Minist\u00e8re des Arm\u00e9es<\/b><br>2018-2019<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Respect, \u00e9coute, soutien Durant mes ann\u00e9es d&rsquo;\u00e9tudes, j&rsquo;ai effectu\u00e9 plusieurs stages au sein d&rsquo;un r\u00e9giment militaire. Malgr\u00e9, les nombreuses difficult\u00e9s et contraintes que les militaires vivent au quotidien. Sur un plan plus personnel, le milieu militaire m&rsquo;a fait d\u00e9couvrir de nombreuses valeurs essentielles \u00e0 l&rsquo;Institution. Le respect de l&rsquo;autre, la responsabilit\u00e9 professionnelle, l&rsquo;engagement et le &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/www.eudinecotte.com\/index.php\/a-mon-propos\/\"> <span class=\"screen-reader-text\">Qui suis-je ?<\/span> Lire la suite\u00a0\u00bb<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-global-header-display":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","footnotes":""},"class_list":["post-214","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Qui suis-je ? - Eudine Cotte<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.eudinecotte.com\/index.php\/a-mon-propos\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Qui suis-je ? - Eudine Cotte\" \/>\n<meta property=\"og:description\" content=\"Respect, \u00e9coute, soutien Durant mes ann\u00e9es d&rsquo;\u00e9tudes, j&rsquo;ai effectu\u00e9 plusieurs stages au sein d&rsquo;un r\u00e9giment militaire. Malgr\u00e9, les nombreuses difficult\u00e9s et contraintes que les militaires vivent au quotidien. Sur un plan plus personnel, le milieu militaire m&rsquo;a fait d\u00e9couvrir de nombreuses valeurs essentielles \u00e0 l&rsquo;Institution. Le respect de l&rsquo;autre, la responsabilit\u00e9 professionnelle, l&rsquo;engagement et le &hellip; Qui suis-je ? Lire la suite\u00a0\u00bb\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eudinecotte.com\/index.php\/a-mon-propos\/\" \/>\n<meta property=\"og:site_name\" content=\"Eudine Cotte\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-18T15:35:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eudinecotte.com\/wp-content\/uploads\/2023\/04\/pexels-art-guzman-8079176-1-1024x683.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eudinecotte.com\\\/index.php\\\/a-mon-propos\\\/\",\"url\":\"https:\\\/\\\/www.eudinecotte.com\\\/index.php\\\/a-mon-propos\\\/\",\"name\":\"Qui suis-je ? - Eudine Cotte\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eudinecotte.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eudinecotte.com\\\/index.php\\\/a-mon-propos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eudinecotte.com\\\/index.php\\\/a-mon-propos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eudinecotte.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/pexels-art-guzman-8079176-1-1024x683.jpg\",\"datePublished\":\"2023-01-18T15:53:35+00:00\",\"dateModified\":\"2023-08-18T15:35:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eudinecotte.com\\\/index.php\\\/a-mon-propos\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.eudinecotte.com\\\/index.php\\\/a-mon-propos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.eudinecotte.com\\\/index.php\\\/a-mon-propos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.eudinecotte.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/pexels-art-guzman-8079176-1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.eudinecotte.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/pexels-art-guzman-8079176-1-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eudinecotte.com\\\/index.php\\\/a-mon-propos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.eudinecotte.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Qui suis-je ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eudinecotte.com\\\/#website\",\"url\":\"https:\\\/\\\/www.eudinecotte.com\\\/\",\"name\":\"Eudine Cotte - Psychologue Clinicienne & Praticienne EFT\",\"description\":\"Psychologue Clinicienne\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.eudinecotte.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Qui suis-je ? - Eudine Cotte","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.eudinecotte.com\/index.php\/a-mon-propos\/","og_locale":"fr_FR","og_type":"article","og_title":"Qui suis-je ? - Eudine Cotte","og_description":"Respect, \u00e9coute, soutien Durant mes ann\u00e9es d&rsquo;\u00e9tudes, j&rsquo;ai effectu\u00e9 plusieurs stages au sein d&rsquo;un r\u00e9giment militaire. Malgr\u00e9, les nombreuses difficult\u00e9s et contraintes que les militaires vivent au quotidien. Sur un plan plus personnel, le milieu militaire m&rsquo;a fait d\u00e9couvrir de nombreuses valeurs essentielles \u00e0 l&rsquo;Institution. Le respect de l&rsquo;autre, la responsabilit\u00e9 professionnelle, l&rsquo;engagement et le &hellip; Qui suis-je ? Lire la suite\u00a0\u00bb","og_url":"https:\/\/www.eudinecotte.com\/index.php\/a-mon-propos\/","og_site_name":"Eudine Cotte","article_modified_time":"2023-08-18T15:35:47+00:00","og_image":[{"url":"https:\/\/www.eudinecotte.com\/wp-content\/uploads\/2023\/04\/pexels-art-guzman-8079176-1-1024x683.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.eudinecotte.com\/index.php\/a-mon-propos\/","url":"https:\/\/www.eudinecotte.com\/index.php\/a-mon-propos\/","name":"Qui suis-je ? - Eudine Cotte","isPartOf":{"@id":"https:\/\/www.eudinecotte.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.eudinecotte.com\/index.php\/a-mon-propos\/#primaryimage"},"image":{"@id":"https:\/\/www.eudinecotte.com\/index.php\/a-mon-propos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eudinecotte.com\/wp-content\/uploads\/2023\/04\/pexels-art-guzman-8079176-1-1024x683.jpg","datePublished":"2023-01-18T15:53:35+00:00","dateModified":"2023-08-18T15:35:47+00:00","breadcrumb":{"@id":"https:\/\/www.eudinecotte.com\/index.php\/a-mon-propos\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eudinecotte.com\/index.php\/a-mon-propos\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.eudinecotte.com\/index.php\/a-mon-propos\/#primaryimage","url":"https:\/\/www.eudinecotte.com\/wp-content\/uploads\/2023\/04\/pexels-art-guzman-8079176-1-scaled.jpg","contentUrl":"https:\/\/www.eudinecotte.com\/wp-content\/uploads\/2023\/04\/pexels-art-guzman-8079176-1-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/www.eudinecotte.com\/index.php\/a-mon-propos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.eudinecotte.com\/"},{"@type":"ListItem","position":2,"name":"Qui suis-je ?"}]},{"@type":"WebSite","@id":"https:\/\/www.eudinecotte.com\/#website","url":"https:\/\/www.eudinecotte.com\/","name":"Eudine Cotte - Psychologue Clinicienne & Praticienne EFT","description":"Psychologue Clinicienne","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eudinecotte.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.eudinecotte.com\/index.php\/wp-json\/wp\/v2\/pages\/214","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eudinecotte.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.eudinecotte.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.eudinecotte.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eudinecotte.com\/index.php\/wp-json\/wp\/v2\/comments?post=214"}],"version-history":[{"count":437,"href":"https:\/\/www.eudinecotte.com\/index.php\/wp-json\/wp\/v2\/pages\/214\/revisions"}],"predecessor-version":[{"id":2901,"href":"https:\/\/www.eudinecotte.com\/index.php\/wp-json\/wp\/v2\/pages\/214\/revisions\/2901"}],"wp:attachment":[{"href":"https:\/\/www.eudinecotte.com\/index.php\/wp-json\/wp\/v2\/media?parent=214"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}